{"id":5622,"date":"2023-11-06T23:58:25","date_gmt":"2023-11-06T20:28:25","guid":{"rendered":"https:\/\/www.ekalato.com\/blog\/?p=5622"},"modified":"2024-07-06T11:03:30","modified_gmt":"2024-07-06T07:33:30","slug":"%d9%85%d9%82%d8%a7%db%8c%d8%b3%d9%87-%d9%82%d8%a7%d8%a8%d9%84%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d8%a7%d9%be%d9%84-%d9%88%d8%a7%da%86-%d8%b3%d8%b1%db%8c-%db%b6-%d9%88-%da%af%d9%84%da%a9%d8%b3%db%8c-%d9%88%d8%a7%da%86-%d8%b3%d8%a7%d9%85%d8%b3%d9%88%d9%86%da%af-%db%b3","status":"publish","type":"post","link":"https:\/\/www.ekalato.com\/blog\/%d9%85%d9%82%d8%a7%db%8c%d8%b3%d9%87-%d9%82%d8%a7%d8%a8%d9%84%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d8%a7%d9%be%d9%84-%d9%88%d8%a7%da%86-%d8%b3%d8%b1%db%8c-%db%b6-%d9%88-%da%af%d9%84%da%a9%d8%b3%db%8c-%d9%88%d8%a7%da%86-%d8%b3%d8%a7%d9%85%d8%b3%d9%88%d9%86%da%af-%db%b3\/","title":{"rendered":"\u0645\u0642\u0627\u06cc\u0633\u0647 \u0642\u0627\u0628\u0644\u06cc\u062a \u0647\u0627\u06cc \u0627\u067e\u0644 \u0648\u0627\u0686 \u0633\u0631\u06cc \u06f6 \u0648 \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u06f3"},"content":{"rendered":"<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0627\u067e\u0644 \u0637\u0644\u0627\u06cc\u0647\u200c\u062f\u0627\u0631 \u0628\u0627\u0632\u0627\u0631\u00a0<span style=\"background-color: #ffff00;\"><a href=\"https:\/\/www.ekalato.com\/watch\">\u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f<\/a><\/span>\u00a0\u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0645\u062f\u062a \u0637\u0648\u0644\u0627\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u0627\u062e\u062a\u0644\u0627\u0641\u060c \u0631\u062a\u0628\u0647 \u0627\u0648\u0644 \u0641\u0631\u0648\u0634 \u062c\u0647\u0627\u0646\u06cc \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0627\u0632 \u06af\u062c\u062a\u200c\u0647\u0627\u06cc \u067e\u0648\u0634\u06cc\u062f\u0646\u06cc \u0631\u0627 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062f\u0627\u0631\u062f. \u0641\u0631\u0648\u0634 \u0628\u0627\u0644\u0627\u06cc \u0627\u067e\u0644 \u0648\u0627\u0686\u200c\u0647\u0627 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u06a9\u06cc\u0641\u06cc\u062a \u0633\u0627\u062e\u062a \u0628\u0627\u0644\u0627 \u0648 \u0645\u0634\u062e\u0635\u0627\u062a \u062c\u0630\u0627\u0628\u060c \u0628\u06cc\u0634 \u0627\u0632 \u0647\u0631 \u0686\u06cc\u0632 \u0645\u062f\u06cc\u0648\u0646 \u0627\u06a9\u0648 \u0633\u06cc\u0633\u062a\u0645 \u06af\u0633\u062a\u0631\u062f\u0647 \u0648 \u0645\u062d\u0628\u0648\u0628 \u0627\u067e\u0644 \u0627\u0633\u062a. \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc\u200c\u0631\u0633\u062f \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0627\u0646\u0628\u0648\u0647 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0633\u0627\u0639\u062a \u0647\u0648\u0634\u0645\u0646\u062f \u0627\u06cc\u0646 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0627\u0633\u062a \u06a9\u0647 \u0627\u0632 \u0646\u0638\u0631 \u0645\u06cc\u0632\u0627\u0646 \u0641\u0631\u0648\u0634 (\u0627\u0644\u0628\u062a\u0647 \u0628\u0627 \u0627\u062e\u062a\u0644\u0627\u0641) \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0631\u0642\u0627\u0628\u062a \u0628\u0627 \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0627\u067e\u0644 \u0628\u067e\u0631\u062f\u0627\u0632\u0646\u062f. \u0627\u0644\u0628\u062a\u0647<span style=\"background-color: #ffff00;\">\u00a0<a href=\"https:\/\/www.ekalato.com\/watch-samsung\">\u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 \u0633\u0627\u0645\u0633\u0648\u0646\u06af<\/a><\/span>\u00a0\u0686\u0647 \u0627\u0632 \u0646\u0638\u0631 \u0645\u0634\u062e\u0635\u0627\u062a \u0641\u0646\u06cc \u0648 \u0686\u0647 \u0627\u0632 \u0646\u0638\u0631 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0628\u0647\u062a\u0631\u06cc\u0646 \u0648 \u0646\u0632\u062f\u06cc\u06a9\u200c\u062a\u0631\u06cc\u0646 \u0631\u0642\u06cc\u0628 \u0628\u0631\u0627\u06cc \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0627\u067e\u0644 \u0628\u0647 \u0634\u0645\u0627\u0631 \u0645\u06cc\u200c\u0631\u0648\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0647 \u0645\u0642\u0627\u06cc\u0633\u0647 \u062f\u0648 \u0645\u062f\u0644\u00a0<a href=\"https:\/\/www.ekalato.com\/watch-apple\"><span style=\"background-color: #ffff00;\">\u0633\u0627\u0639\u062a \u0647\u0648\u0634\u0645\u0646\u062f \u0627\u067e\u0644<\/span><\/a>\u00a0\u0648\u0627\u0686 6 \u0648\u00a0<span style=\"background-color: #ffff00;\"><a href=\"https:\/\/www.ekalato.com\/galaxy-watch3-r840\">\u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af<\/a><\/span>\u00a0\u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645 \u06a9\u0647 \u062f\u0631 \u0633\u0627\u0644 2020 \u0645\u06cc\u0644\u0627\u062f\u06cc \u0648 \u062f\u0631 \u0641\u0627\u0635\u0644\u0647 \u06a9\u0645\u062a\u0631 \u0627\u0632 \u062f\u0648 \u0645\u0627\u0647 \u0645\u0639\u0631\u0641\u06cc \u0634\u062f\u0646\u062f \u0648 \u0628\u0647 \u062c\u0631\u0623\u062a \u0628\u0647\u062a\u0631\u06cc\u0646 \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0628\u0627\u0632\u0627\u0631 \u062f\u0631 \u0622\u0646 \u0633\u0627\u0644 \u0647\u0633\u062a\u0646\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p dir=\"rtl\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-5624 size-full\" src=\"https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-2_1000.jpeg\" alt=\"\u0645\u0642\u0627\u06cc\u0633\u0647 apple watch 6 \u0628\u0627 Galaxy Watch 3\" width=\"1000\" height=\"667\" srcset=\"https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-2_1000.jpeg 1000w, https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-2_1000-300x200.jpeg 300w, https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-2_1000-768x512.jpeg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<h2 dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0645\u0634\u062e\u0635\u0627\u062a \u0627\u067e\u0644 \u0648\u0627\u0686 \u0633\u0631\u06cc 6 \u0648 \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af<\/span><\/h2>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<h3 dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0639\u0645\u0644\u06a9\u0631\u062f \u0627\u067e\u0644 \u0648\u0627\u0686 \u0633\u0631\u06cc 6 \u0648 \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af<\/span><\/h3>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0647\u0645\u0627\u0646\u200c\u0637\u0648\u0631 \u06a9\u0647 \u062f\u0631 \u0628\u0627\u0644\u0627 \u0646\u06cc\u0632 \u0627\u0634\u0627\u0631\u0647 \u0634\u062f \u062f\u0631 \u0645\u0642\u0627\u06cc\u0633\u0647 Apple Watch 6 \u0648 Galaxy Watch 3 \u0628\u0627 \u0628\u0631\u062a\u0631\u06cc\u0646 \u0645\u062f\u0644\u200c\u0647\u0627\u06cc \u067e\u0631\u0686\u0645\u062f\u0627\u0631 \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f 2020 \u0631\u0648 \u0628\u0647 \u0631\u0648 \u0647\u0633\u062a\u06cc\u0645. \u0648\u0627\u0686 6 \u0627\u067e\u0644 \u0628\u0647 \u0635\u0648\u0631\u062a \u067e\u06cc\u0634\u200c\u0641\u0631\u0636 \u0633\u06cc\u0633\u062a\u0645 \u0639\u0627\u0645\u0644 watchOS 7.0 \u0631\u0627 \u0627\u062c\u0631\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0627\u0645\u06a9\u0627\u0646 \u0628\u0647\u200c\u0631\u0648\u0632\u0631\u0633\u0627\u0646\u06cc \u0622\u0646 \u0628\u0647 \u0646\u0633\u062e\u0647\u200c\u0647\u0627\u06cc \u0628\u0627\u0644\u0627\u062a\u0631 \u0641\u0631\u0627\u0647\u0645 \u0627\u0633\u062a. \u0627\u067e\u0644 \u062f\u0631 \u0627\u06cc\u0646 \u0633\u0631\u06cc \u0627\u0632 \u062a\u0631\u0627\u0634\u0647 Apple A6 \u0628\u0627 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647 \u062f\u0648 \u0647\u0633\u062a\u0647\u200c\u0627\u06cc 1.8 \u06af\u06cc\u06af\u0627\u0647\u0631\u062a\u0632 \u0648 \u06af\u0631\u0627\u0641\u06cc\u06a9 PowerVR \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f\u0647 \u062a\u0645\u0627\u0645\u06cc \u0633\u0627\u06cc\u0632\u0647\u0627\u06cc \u0627\u067e\u0644 \u0648\u0627\u0686 6 \u062f\u0627\u0631\u0627\u06cc \u062f\u0648 \u0646\u0633\u062e\u0647 \u0628\u0644\u0648\u062a\u0648\u062b \u0648 LTE \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0634\u0628\u06a9\u0647 \u0645\u062e\u0627\u0628\u0631\u0627\u062a\u06cc \u0646\u0633\u062e\u0647 LTE \u0628\u0647 \u0639\u0644\u062a \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631\u06cc \u0627\u0632 eSIM \u0648 \u0639\u062f\u0645 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u067e\u0631\u0627\u062a\u0648\u0631\u0647\u0627 \u062f\u0631 \u0627\u06cc\u0631\u0627\u0646 \u0628\u0644\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0633\u062a. \u0627\u0632 \u062f\u06cc\u06af\u0631 \u0645\u0634\u062e\u0635\u0627\u062a \u0633\u062d\u062a\u200c\u0627\u0641\u0632\u0627\u0631\u06cc \u0627\u067e\u0644 \u0648\u0627\u0686 6 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 GPS \u062f\u0627\u062e\u0644\u06cc\u060c \u0628\u0644\u0648\u062a\u0648\u062b 5.0\u060c \u0634\u0628\u06a9\u0647 Wi-Fi \u062f\u0648\u0628\u0627\u0646\u062f\u0647\u060c 1 \u06af\u06cc\u06af\u0627\u0628\u0627\u06cc\u062a \u0631\u0645 \u0648 32 \u06af\u06cc\u06af\u0627\u0628\u0627\u06cc\u062a \u062d\u0627\u0641\u0638\u0647 \u062f\u0627\u062e\u0644\u06cc \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0627\u0632 \u062a\u0631\u0627\u0634\u0647 10 \u0646\u0627\u0646\u0648\u0645\u062a\u0631\u06cc Exynos 9110 \u0628\u0627 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647 \u062f\u0648 \u0647\u0633\u062a\u0647\u200c\u0627\u06cc 1.15 \u06af\u06cc\u06af\u0627\u0647\u0631\u062a\u0632 \u0648 \u06af\u0631\u0627\u0641\u06cc\u06a9 Mali-T720 \u0628\u0647\u0631\u0647 \u0645\u06cc\u200c\u0628\u0631\u062f. \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0646\u06cc\u0632 \u062f\u0631 \u0646\u0633\u062e\u0647\u200c\u0647\u0627\u06cc \u0628\u0644\u0648\u062a\u0648\u062b \u0648 LTE \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0646\u0633\u062e\u0647 LTE \u0628\u0647 \u062f\u0644\u0627\u06cc\u0644 \u0645\u0634\u0627\u0628\u0647 \u0627\u0632 \u0627\u067e\u0631\u0627\u062a\u0648\u0631\u0647\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646\u06cc \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0646\u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u0632 \u062f\u06cc\u06af\u0631 \u0645\u0634\u062e\u0635\u0627\u062a \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u0633\u06cc\u0633\u062a\u0645 \u0639\u0627\u0645\u0644 Tizen OS 5.5\u060c \u0628\u0644\u0648\u062a\u0648\u062b 5.0\u060c \u0634\u0628\u06a9\u0647 Wi-Fi\u060c GPS \u062f\u0627\u062e\u0644\u06cc\u060c 1 \u06af\u06cc\u06af\u0627\u0628\u0627\u06cc\u062a \u0631\u0645 \u0648 \u062a\u0627 8 \u06af\u06cc\u06af\u0627\u0628\u0627\u06cc\u062a \u062d\u0627\u0641\u0638\u0647 \u062f\u0627\u062e\u0644\u06cc \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f. \u0627\u06af\u0631 \u0633\u0627\u0639\u062a \u0647\u0648\u0634\u0645\u0646\u062f Galaxy Watch 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0639\u0645\u0644\u06a9\u0631\u062f\u06cc \u0642\u062f\u0631\u062a\u0645\u0646\u062f \u0648 \u0639\u0627\u0644\u06cc \u062f\u0627\u0631\u062f\u061b \u0627\u0645\u0627 \u0646\u062a\u06cc\u062c\u0647 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0639\u0645\u0644\u06a9\u0631\u062f \u0645\u06cc\u0627\u0646 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0648 Apple Watch 6 \u0628\u0627 \u0628\u0631\u062a\u0631\u06cc \u0633\u0627\u0639\u062a \u0647\u0648\u0634\u0645\u0646\u062f \u0627\u067e\u0644 \u0647\u0645\u0631\u0627\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<h3 dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0645\u0642\u0627\u0648\u0645\u062a \u0633\u0627\u0639\u062a \u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0648 \u0627\u067e\u0644 \u0648\u0627\u0686 6 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0622\u0628<\/span><\/h3>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0628\u0631\u0646\u062f\u0647\u0627\u06cc \u0645\u0637\u0631\u062d \u0647\u0645\u06af\u06cc \u0627\u0632 \u0645\u0642\u0627\u0648\u0645\u062a \u062e\u0648\u0628\u06cc \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0646\u0641\u0648\u0630 \u06af\u0631\u062f \u0648 \u063a\u0628\u0627\u0631 \u0648 \u0622\u0628 (\u0627\u063a\u0644\u0628 \u0645\u062c\u0647\u0632 \u0628\u0647 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647 IP68) \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0647\u0633\u062a\u0646\u062f. \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u067e\u0627 \u0631\u0627 \u0627\u0632 \u0627\u06cc\u0646 \u0646\u06cc\u0632 \u0641\u0631\u0627\u062a\u0631 \u0645\u06cc\u200c\u200c\u06af\u0630\u0627\u0631\u062f \u0648 \u0627\u0632 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627 \u0648 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u062d\u0631\u0641\u0647\u200c\u0627\u06cc\u200c\u062a\u0631 \u0648 \u0645\u0642\u0627\u0648\u0645\u062a \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0644\u0627\u062a\u0631\u06cc \u0628\u0647\u0631\u0647 \u0645\u06cc\u200c\u0628\u0631\u062f. \u062f\u0631 \u0628\u062e\u0634 \u0645\u0642\u0627\u0645\u062a \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0622\u0628 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0628\u0627 \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631\u06cc \u0627\u0632 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647 5ATM \u062a\u0627 \u0639\u0645\u0642 50 \u0645\u062a\u0631\u06cc \u0642\u0627\u0628\u0644\u06cc\u062a \u0636\u062f \u0622\u0628 \u0628\u0648\u062f\u0646 \u062e\u0648\u062f \u0631\u0627 \u062d\u0641\u0638 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0631\u0627\u06cc \u0648\u0631\u0632\u0634\u200c\u0647\u0627\u06cc \u0622\u0628\u06cc \u0627\u0632 \u0642\u0628\u06cc\u0644 \u0634\u0646\u0627 \u0646\u06cc\u0632 \u0645\u0646\u0627\u0633\u0628 \u0627\u0633\u062a. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644 \u0628\u0627 \u0628\u062f\u0646\u0647 \u0645\u0642\u0627\u0648\u0645 \u062e\u0648\u062f \u0628\u0627 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0646\u0638\u0627\u0645\u06cc MIL-STD-810G \u0633\u0627\u0632\u06af\u0627\u0631\u06cc \u062f\u0627\u0631\u062f. \u0627\u067e\u0644 \u0648\u0627\u0686 6 \u0646\u06cc\u0632 \u0645\u0627\u0646\u0646\u062f \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0627\u0632 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647 5ATM \u0648 \u0645\u0642\u0627\u0648\u0645\u062a \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0622\u0628 \u062a\u0627 \u0639\u0645\u0642 50 \u0645\u062a\u0631 \u0628\u0647\u0631\u0647 \u0645\u06cc\u200c\u0628\u0631\u062f \u0648 \u0647\u0631 \u0686\u0646\u062f \u0627\u0632 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0646\u0638\u0627\u0645\u06cc \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0646\u0645\u06cc\u200c\u06a9\u0646\u062f\u061b \u0627\u0645\u0627 \u0628\u0647 \u0647\u0631 \u062d\u0627\u0644 \u0628\u062f\u0646\u0647 \u0628\u0633\u06cc\u0627\u0631 \u0645\u062d\u06a9\u0645 \u0648 \u0628\u0627 \u062f\u0648\u0627\u0645\u06cc \u062f\u0627\u0631\u062f. \u06af\u0641\u062a\u0646\u06cc \u0627\u0633\u062a \u0639\u0644\u06cc\u200c\u0631\u063a\u0645 \u0645\u0642\u0627\u0648\u0645\u062a \u0628\u0627\u0644\u0627\u06cc \u0647\u0631 \u062f\u0648 \u0645\u062f\u0644\u060c \u062d\u062f\u0627\u0642\u0644 \u0627\u0632 \u0646\u0638\u0631 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627 \u0648 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647\u200c\u0647\u0627 \u0648 \u0631\u0648\u06cc \u06a9\u0627\u063a\u0630 \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0627\u0632 \u0634\u0631\u0627\u06cc\u0637 \u0628\u0647\u062a\u0631\u06cc \u062f\u0631 \u0627\u06cc\u0646 \u0632\u0645\u06cc\u0646\u0647 \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0627\u0633\u062a.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\"> <img decoding=\"async\" class=\"aligncenter wp-image-5625 size-full\" src=\"https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-3_1000.jpeg\" alt=\"\u0645\u0642\u0627\u06cc\u0633\u0647 \u0637\u0631\u0627\u062d\u06cc \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0648 \u0627\u067e\u0644 \u0648\u0627\u0686 6\" width=\"1000\" height=\"667\" srcset=\"https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-3_1000.jpeg 1000w, https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-3_1000-300x200.jpeg 300w, https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-3_1000-768x512.jpeg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/span><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<h3 dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0642\u0627\u0628\u0644\u06cc\u062a \u0645\u06a9\u0627\u0644\u0645\u0647 \u0627\u067e\u0644 \u0648\u0627\u0686 \u0633\u0631\u06cc 6 \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3<\/span><\/h3>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0633\u0627\u0639\u062a \u0647\u0648\u0634\u0645\u0646\u062f Galaxy Watch 3 \u0648 Apple Watch 6\u060c \u0647\u0631 \u062f\u0648 \u0627\u0632 \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u0627\u0631\u062a\u0628\u0627\u0637\u06cc \u062e\u0648\u0628\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631\u0646\u062f. \u0647\u0631 \u062f\u0648 \u0645\u062d\u0635\u0648\u0644 \u0628\u0627 \u0627\u062a\u0635\u0627\u0644 \u0628\u0647 \u06af\u0648\u0634\u06cc \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0628\u0644\u0648\u062a\u0648\u062b \u0628\u0627 \u0628\u0647 \u0648\u0633\u06cc\u0644\u0647 \u0634\u0628\u06a9\u0647 Wi-Fi \u0627\u0645\u06a9\u0627\u0646 \u062f\u0631\u06cc\u0627\u0641\u062a \u0646\u0648\u062a\u06cc\u0641\u06cc\u06a9\u06cc\u0634\u0646 \u0648 \u0627\u0639\u0644\u0627\u0646 \u062a\u0645\u0627\u0633 \u0631\u0627 \u062f\u0627\u0631\u0646\u062f. \u06a9\u0627\u0631\u0628\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u0645\u0627\u0633 \u0631\u0627 \u0642\u0628\u0648\u0644 \u06cc\u0627 \u0631\u062f \u06a9\u0646\u062f \u0648 \u062f\u0631 \u0635\u0648\u0631\u062a \u0642\u0628\u0648\u0644 \u062a\u0645\u0627\u0633 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0647\u0646\u062f\u0632\u0641\u0631\u06cc \u0628\u0644\u0648\u062a\u0648\u062b \u06cc\u0627 \u0645\u06cc\u06a9\u0631\u0648\u0641\u0648\u0646 \u0648 \u0627\u0633\u067e\u06cc\u06a9\u0631 \u0633\u0627\u0639\u062a \u0628\u0647 \u0627\u0646\u062c\u0627\u0645 \u0645\u06a9\u0627\u0644\u0645\u0647 \u0628\u067e\u0631\u062f\u0627\u0632\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u062f\u0631 \u0645\u0627\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u067e\u0631\u0627\u062a\u0648\u0631\u0647\u0627\u06cc \u0622\u0646\u0647\u0627 \u0627\u0632 eSIM \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0646\u0633\u062e\u0647 LTE \u0647\u0631 \u062f\u0648 \u0645\u062d\u0635\u0648\u0644 \u0642\u0627\u0628\u0644\u06cc\u062a \u0645\u06a9\u0627\u0644\u0645\u0647 \u0648 \u0627\u062a\u0635\u0627\u0644 \u0628\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u0633\u062a\u0642\u0644 \u0631\u0627 \u062f\u0627\u0631\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<h3 dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0639\u0645\u0631 \u0628\u0627\u062a\u0631\u06cc \u0627\u067e\u0644 \u0648\u0627\u0686 \u0633\u0631\u06cc 6 \u0648 \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af<\/span><\/h3>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0627\u067e\u0644 \u0648 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0647\u0645\u0648\u0627\u0631\u0647 \u0628\u0647 \u0634\u0627\u0631\u0698\u062f\u0647\u06cc \u0648 \u0645\u0627\u0646\u062f\u06af\u0627\u0631\u06cc \u0628\u0627\u0644\u0627\u06cc \u0628\u0627\u062a\u0631\u06cc \u0634\u0647\u0631\u062a \u062f\u0627\u0634\u062a\u0647\u200c\u0627\u0646\u062f. \u06af\u0644\u06a9\u0633 \u0648\u0627\u0686 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0646\u06cc\u0632 \u0627\u0632 \u0628\u0627\u062a\u0631\u06cc 350 \u0645\u06cc\u0644\u06cc\u200c\u0622\u0645\u067e\u0631\u0633\u0627\u0639\u062a \u0645\u062c\u0647\u0632 \u0627\u0633\u062a \u0648 \u062f\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0631\u0645\u0627\u0644 \u0642\u0627\u062f\u0631 \u0627\u0633\u062a \u062a\u0627 \u062f\u0648 \u0631\u0648\u0632 \u0645\u0627\u0646\u062f\u06af\u0627\u0631\u06cc \u0634\u0627\u0631\u0698 \u0627\u0631\u0627\u0626\u0647 \u06a9\u0646\u062f. \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0627\u067e\u0644 \u0648\u0627\u0686 \u0633\u0631\u06cc 6 \u0628\u0647 \u06cc\u06a9 \u0628\u0627\u062a\u0631\u06cc 304 \u0645\u06cc\u0644\u06cc\u200c\u0622\u0645\u067e\u0631 \u0633\u0627\u0639\u062a \u0645\u062c\u0647\u0632 \u0634\u062f\u0647 \u06a9\u0647 \u0642\u0627\u062f\u0631 \u0627\u0633\u062a \u062f\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u0639\u0645\u0648\u0644\u06cc \u062a\u0627 18 \u0633\u0627\u0639\u062a \u062f\u0648\u0627\u0645 \u0628\u06cc\u0627\u0648\u0631\u062f. \u06af\u0641\u062a\u0646\u06cc \u0627\u0633\u062a \u0647\u0631 \u062f\u0648 \u0633\u0627\u0639\u062a \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0622\u062f\u0627\u067e\u062a\u0648\u0631 \u0628\u06cc\u200c\u0633\u06cc\u0645 \u0645\u063a\u0646\u0627\u0637\u06cc\u0633\u06cc \u0648 \u0628\u0627 \u0641\u0646\u0627\u0648\u0631\u06cc Qi \u0634\u0627\u0631\u0698 \u0645\u06cc\u200c\u06af\u0631\u062f\u0646\u062f.<\/span><\/p>\n<p dir=\"rtl\"><img decoding=\"async\" class=\"aligncenter wp-image-5623 size-full\" src=\"https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-1_1000.jpeg\" alt=\"\u0645\u0642\u0627\u06cc\u0633\u0647 \u0645\u0634\u062e\u0635\u0627\u062a \u0641\u0646\u06cc \u0633\u0627\u0639\u062a \u0647\u0648\u0634\u0645\u0646\u062f Apple Watch 6 \u0648 Galaxy Watch 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \" width=\"1000\" height=\"667\" srcset=\"https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-1_1000.jpeg 1000w, https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-1_1000-300x200.jpeg 300w, https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-1_1000-768x512.jpeg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<h3 dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0635\u0641\u062d\u0647 \u0646\u0645\u0627\u06cc\u0634 \u0633\u0627\u0639\u062a \u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0648 \u0627\u067e\u0644 \u0648\u0627\u0686 6<\/span><\/h3>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0645\u062f\u0644\u200c\u0647\u0627\u06cc \u0628\u0627 \u0627\u0628\u0639\u0627\u062f \u0628\u0632\u0631\u06af\u062a\u0631 \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0645\u0648\u0631\u062f \u0628\u062d\u062b \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647\u060c \u0627\u0632 \u0646\u0645\u0627\u06cc\u0634\u06af\u0631\u0647\u0627\u06cc OLED \u0628\u0647\u0631\u0647 \u0645\u06cc\u200c\u0628\u0631\u0646\u062f \u06a9\u0647 \u06a9\u06cc\u0641\u06cc\u062a \u0648 \u062e\u0648\u0627\u0646\u0627\u06cc\u06cc \u0628\u0633\u06cc\u0627\u0631 \u062e\u0648\u0628\u06cc \u062f\u0627\u0631\u0646\u062f. \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0627\u0632 \u06cc\u06a9 \u067e\u0646\u0644 1.4 \u0627\u06cc\u0646\u0686 SuperAMOLED \u0628\u0627 \u0631\u0632\u0648\u0644\u0648\u0634\u0646 360&#215;360 \u067e\u06cc\u06a9\u0633\u0644 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0628\u0647 \u0642\u0627\u0628\u0644\u06cc\u062a \u0646\u0645\u0627\u06cc\u0634\u06af\u0631 \u0647\u0645\u06cc\u0634\u0647 \u0631\u0648\u0634\u0646 AOD \u0648 \u067e\u0648\u0634\u0634 \u0645\u062d\u0627\u0641\u0638 \u06af\u0648\u0631\u06cc\u0644\u0627\u06af\u0644\u0633 DX \u0645\u062c\u0647\u0632 \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u0632 \u0633\u0648\u06cc \u062f\u06cc\u06af\u0631 \u0627\u067e\u0644 \u0648\u0627\u0686 6 \u0627\u0632 \u06cc\u06a9 \u0646\u0645\u0627\u06cc\u0634\u06af\u0631 1.7 \u0627\u06cc\u0646\u0686 LTPO OLED \u0628\u0627 \u0631\u0632\u0648\u0644\u0648\u0634\u0646 448&#215;368\u060c \u0642\u0627\u0628\u0644\u06cc\u062a \u0646\u0645\u0627\u06cc\u0634\u06af\u0631 \u0647\u0645\u06cc\u0634\u0647 \u0631\u0648\u0634\u0646 AOD \u0648 \u067e\u0648\u0634\u0634 \u0645\u062d\u0627\u0641\u0638 \u06cc\u0627\u0642\u0648\u062a \u06a9\u0628\u0648\u062f \u0628\u0647\u0631\u0647 \u0645\u06cc\u200c\u0628\u0631\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0646\u0648\u0639 \u0648 \u0627\u0646\u062f\u0627\u0632\u0647 \u0635\u0641\u062d\u0647 \u0646\u0645\u0627\u06cc\u0634\u060c \u0627\u067e\u0644 \u0648\u0627\u0686 6 \u0627\u0632 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627\u062a\u0631 \u0648 \u0627\u0628\u0639\u0627\u062f \u0628\u0632\u0631\u06af\u062a\u0631\u06cc \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631 \u0627\u0633\u062a.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<h3 dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0637\u0631\u0627\u062d\u06cc \u0648 \u0627\u0646\u062f\u0627\u0632\u0647 \u0648 \u0645\u062f\u0644 \u0627\u067e\u0644 \u0648\u0627\u0686 \u0633\u0631\u06cc 6 \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3<\/span><\/h3>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0637\u0631\u0627\u062d\u06cc \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0627\u067e\u0644 \u0648 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u062f\u0631 \u0686\u0646\u062f \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u06cc\u06a9 \u0627\u0632 \u062a\u0641\u0627\u0648\u062a\u200c\u0647\u0627\u06cc \u0627\u0635\u0644\u06cc \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0628\u0648\u062f\u0647 \u0627\u0633\u062a. \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u067e\u0633 \u0627\u0632 \u062a\u063a\u06cc\u06cc\u0631 \u0645\u0627\u0647\u06cc\u062a \u06af\u062c\u062a\u200c\u0647\u0627\u06cc \u067e\u0648\u0634\u06cc\u062f\u0646\u06cc \u062e\u0648\u062f \u0648 \u062a\u063a\u06cc\u06cc\u0631 \u0646\u0627\u0645 \u062f\u0633\u062a\u0647\u200c\u0628\u0646\u062f\u06cc \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0627\u0632 Gear \u0628\u0647 Galaxy \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0641\u0631\u0645 \u0641\u06a9\u062a\u0648\u0631 \u0645\u0631\u0628\u0639\u06cc \u062f\u0631 \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u062e\u0648\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u06a9\u0631\u062f\u0647 \u0648 \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0627\u067e\u0644 \u0646\u06cc\u0632 \u0647\u0631\u06af\u0632 \u062a\u0645\u0627\u06cc\u0644\u06cc \u0628\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0641\u0631\u0645 \u0641\u06a9\u062a\u0648\u0631\u06cc \u0628\u0647 \u063a\u06cc\u0631 \u0627\u0632 \u0645\u0631\u0628\u0639 \u0648 \u0686\u0647\u0627\u0631\u06af\u0648\u0634 \u062f\u0631 \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0646\u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a. \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0646\u06cc\u0632 \u0627\u0632 \u0637\u0631\u0627\u062d\u06cc \u06af\u0631\u062f \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u0648 \u062d\u0627\u0634\u06cc\u0647 \u0686\u0631\u062e\u0627\u0646 \u0645\u0634\u0647\u0648\u0631 \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0628\u0647\u0631\u0647 \u0645\u06cc\u200c\u0628\u0631\u062f. \u0627\u06cc\u0646 \u0633\u0627\u0639\u062a \u062f\u0631 \u062f\u0648 \u0633\u0627\u06cc\u0632 41 \u0648 45 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631\u06cc\u060c \u0628\u0627 \u062c\u0646\u0633 \u0628\u062f\u0646\u0647 \u0627\u0633\u062a\u06cc\u0644 \u0636\u062f \u0632\u0646\u06af 316L \u06cc\u0627 \u062a\u06cc\u062a\u0627\u0646\u06cc\u0648\u0645\u06cc \u0648 \u062f\u0631 \u0631\u0646\u06af\u200c\u0647\u0627\u06cc \u0628\u0631\u0646\u0632\u060c \u0645\u0634\u06a9\u06cc \u0648 \u0633\u0641\u06cc\u062f \u0639\u0631\u0636\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0627\u067e\u0644 \u0648\u0627\u0686 6 \u0628\u0627 \u0641\u0631\u0645 \u0641\u06a9\u062a\u0648\u0631 \u0647\u0645\u06cc\u0634\u06af\u06cc \u0686\u0647\u0627\u0631\u06af\u0648\u0634 \u062e\u0648\u062f \u062f\u0631 \u062f\u0648 \u0633\u0627\u06cc\u0632 40 \u0648 44 \u0645\u06cc\u0644\u06cc\u200c\u0645\u062a\u0631\u06cc\u060c \u062c\u0646\u0633 \u0628\u062f\u0646\u0647 \u0622\u0644\u0648\u0645\u06cc\u0646\u06cc\u0648\u0645 \u06cc\u0627 \u062a\u06cc\u062a\u0627\u0646\u06cc\u0648\u0645 \u06cc\u0627 \u0627\u0633\u062a\u06cc\u0644 \u0636\u062f \u0632\u0646\u06af \u0639\u0631\u0636\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u067e\u0644 \u0648\u0627\u0686 \u0633\u0631\u06cc 6 \u0628\u0627 \u0628\u062f\u0646\u0647 \u0622\u0644\u0648\u0645\u06cc\u06cc\u0646\u06cc\u0648\u0645 \u0627\u0648\u0644\u06cc\u0646 \u0633\u0631\u06cc \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0627\u06cc\u0646 \u0628\u0631\u0646\u062f \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u0641\u0631\u06cc\u0645 \u0622\u0644\u0648\u0645\u06cc\u0646\u06cc\u0648\u0645\u06cc \u0631\u0646\u06af\u06cc \u0648 \u062f\u0631 \u0631\u0646\u06af\u200c\u0647\u0627\u06cc \u0645\u062a\u0646\u0648\u0639 \u0648 \u062c\u0630\u0627\u0628 \u0642\u0631\u0645\u0632\u060c \u0622\u0628\u06cc\u060c \u0646\u0642\u0631\u0647\u200c\u0627\u06cc\u060c \u0637\u0644\u0627\u06cc\u06cc \u0648 \u062e\u0627\u06a9\u0633\u062a\u0631\u06cc \u0631\u0648\u0627\u0646\u0647 \u0628\u0627\u0632\u0627\u0631 \u0634\u062f. \u0647\u0631 \u062f\u0648 \u0633\u0627\u0639\u062a \u0647\u0648\u0634\u0645\u0646\u062f \u0645\u0648\u0631\u062f \u0628\u062d\u062b \u062f\u0631 \u0646\u0648\u0639 \u062e\u0648\u062f \u0632\u06cc\u0628\u0627 \u0648 \u0639\u0627\u0644\u06cc \u0647\u0633\u062a\u0646\u062f\u060c \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0637\u0631\u0627\u062d\u06cc \u06a9\u0644\u0627\u0633\u06cc\u06a9 \u0648 \u0627\u067e\u0644 \u0637\u0631\u0627\u062d\u06cc \u0645\u062f\u0631\u0646\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u00a0\u06a9\u0646\u062f \u0648 \u0628\u0631\u062a\u0631\u06cc \u0647\u0631 \u06a9\u062f\u0627\u0645 \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0637\u0631\u0627\u062d\u06cc \u06a9\u0627\u0645\u0644\u0627\u064b \u0628\u0647 \u0633\u0644\u06cc\u0642\u0647 \u06a9\u0627\u0631\u0628\u0631 \u0628\u0633\u062a\u06af\u06cc \u062f\u0627\u0631\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<h3 dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0631\u062f\u06cc\u0627\u0628\u06cc \u0641\u06cc\u062a\u0646\u0633 \u0648 \u0633\u0644\u0627\u0645\u062a \u0627\u067e\u0644 \u0648\u0627\u0686 \u0633\u0631\u06cc 6 \u0648 \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 \u0633\u0627\u0645\u0633\u0648\u0646\u06af 3<\/span><\/h3>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0628\u0631\u0646\u062f\u0647\u0627\u06cc \u0627\u067e\u0644 \u0648 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0647\u0631 \u062f\u0648 \u0627\u0632 \u062c\u0645\u0644\u0647 \u06a9\u0645\u067e\u0627\u0646\u06cc\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u0631\u0648 \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0627\u0631\u0627\u0626\u0647 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u0633\u0644\u0627\u0645\u062a\u06cc\u060c \u067e\u0632\u0634\u06a9\u06cc \u0648 \u0648\u0631\u0632\u0634\u06cc \u0631\u0648\u06cc \u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0647\u0633\u062a\u0646\u062f \u0648 \u062f\u0648 \u0633\u0627\u0639\u062a \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u062c 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0648 \u0627\u067e\u0644 \u0648\u0627\u0686 6 \u0631\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0622\u063a\u0627\u0632 \u062f\u0648\u0631\u0647 \u0637\u0644\u0627\u06cc\u06cc \u0648 \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0627\u0631\u0627\u0626\u0647 \u0627\u06cc\u0646 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627 \u0631\u0648\u06cc \u06af\u062c\u062a\u200c\u0647\u0627\u06cc \u067e\u0648\u0634\u06cc\u062f\u0646\u06cc \u062f\u0627\u0646\u0633\u062a. \u0647\u0631 \u062f\u0648 \u0633\u0627\u0639\u062a \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u062a\u0646\u062f\u0631\u0633\u062a\u06cc\u060c \u0641\u06cc\u062a\u0646\u0633 \u0648 \u0648\u0631\u0632\u0634\u06cc \u0645\u062a\u0646\u0648\u0639 \u0648 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 \u0627\u067e\u0644\u06cc\u06a9\u06cc\u0634\u0646\u200c\u0647\u0627\u06cc \u0627\u062e\u062a\u0635\u0627\u0635\u06cc \u0648 \u0634\u062e\u0635 \u062b\u0627\u0644\u062b \u0645\u062a\u0646\u0648\u0639 (\u06a9\u0647 \u0627\u0644\u0628\u062a\u0647 \u062f\u0631 \u0627\u067e\u0644 \u0648\u0627\u0686\u200c\u0647\u0627 \u0645\u062a\u0646\u0648\u0639\u200c\u062a\u0631 \u0646\u06cc\u0632 \u0647\u0633\u062a\u0646\u062f) \u0627\u0632 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0646\u0638\u06cc\u0631 \u067e\u0627\u06cc\u0634 \u0636\u0631\u0628\u0627\u0646 \u0642\u0644\u0628\u060c \u0627\u06a9\u0633\u06cc\u0698\u0646 \u062e\u0648\u0646 SPO2\u060c \u0627\u0644\u06a9\u062a\u0631\u0648\u06a9\u0627\u0631\u062f\u06cc\u0648\u06af\u0631\u0627\u0641\u06cc (ECG) \u06cc\u0627 \u0646\u0648\u0627\u0631 \u0642\u0644\u0628 \u0648 \u0633\u0646\u062c\u0634 \u06a9\u06cc\u0641\u06cc\u062a \u062e\u0648\u0627\u0628 \u0628\u0631\u062e\u0648\u0631\u062f\u0627\u0631\u0646\u062f\u061b \u0627\u0645\u0627 \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0628\u0627 \u0645\u0627\u0647\u06cc\u062a \u067e\u0632\u0634\u06a9\u06cc \u0633\u0627\u0639\u062a\u200c\u200c\u0647\u0627\u06cc Apple Watch 6 \u0648 Galaxy Watch 3 \u0641\u0642\u0637 \u062f\u0631 \u0645\u0646\u0627\u0637\u0642\u06cc \u0641\u0639\u0627\u0644 \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0633\u06cc\u0633\u062a\u0645 \u0648 \u0646\u0638\u0627\u0645 \u067e\u0632\u0634\u06a9\u06cc \u0645\u0631\u0628\u0648\u0637\u0647 \u0628\u0647 \u0635\u0648\u0631\u062a \u0631\u0633\u0645\u06cc \u0622\u0646\u0647\u0627 \u0631\u0627 \u062a\u0623\u06cc\u06cc\u062f \u06a9\u0631\u062f\u0647 \u0628\u0627\u0634\u0646\u062f \u0648 \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062c\u0647\u062a \u062f\u0631 \u0627\u06cc\u0631\u0627\u0646 \u0648 \u0628\u0633\u06cc\u0627\u0631\u06cc \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u0641\u0639\u0627\u0644 \u0648 \u0642\u0627\u0628\u0644 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u06cc\u0633\u062a\u0646\u062f.<\/span><\/p>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p dir=\"rtl\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5626 size-full\" src=\"https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-4_1000.jpeg\" alt=\"\u0645\u0642\u0627\u06cc\u0633\u0647 \u0642\u0627\u0628\u0644\u06cc\u062a \u0647\u0627\u06cc \u062a\u0646\u062f\u0631\u0633\u062a\u06cc \u0648 \u0633\u0644\u0627\u0645\u062a\u06cc \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0628\u0627 \u0648\u0627\u0686 6 \u0627\u067e\u0644\" width=\"1000\" height=\"667\" srcset=\"https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-4_1000.jpeg 1000w, https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-4_1000-300x200.jpeg 300w, https:\/\/www.ekalato.com\/blog\/wp-content\/uploads\/2024\/06\/apple-watch-6-vs-Galaxy-Watch-3-4_1000-768x512.jpeg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<h2 dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u0645\u0642\u0627\u06cc\u0633\u0647 \u0642\u06cc\u0645\u062a \u0648 \u0627\u0631\u0632\u0634 \u062e\u0631\u06cc\u062f \u0633\u0627\u0639\u062a \u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0648 \u0627\u067e\u0644 \u0648\u0627\u0686 6<\/span><\/h2>\n<p dir=\"rtl\" style=\"text-align: justify;\"><span style=\"color: #000000;\">\u062f\u0631 \u0632\u0645\u0627\u0646 \u0645\u0639\u0631\u0641\u06cc (\u0633\u0627\u0644 2020 \u0645\u06cc\u0644\u0627\u062f\u06cc) \u0647\u0631 \u062f\u0648 \u0633\u0627\u0639\u062a \u0647\u0648\u0634\u0645\u0646\u062f Galaxy Watch 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0648 \u0627\u067e\u0644 Watch 6 \u062f\u0631 \u0628\u0627\u0632\u0647 \u0648 \u0631\u0646\u062c \u0642\u06cc\u0645\u062a\u06cc \u0645\u0634\u0627\u0628\u0647\u06cc \u0642\u0631\u0627\u0631 \u062f\u0627\u0634\u062a\u0646\u062f\u060c \u0627\u0645\u0627 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0641\u0639\u0644\u06cc \u0648 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0639\u0631\u0636\u0647 \u0645\u062f\u0644\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f\u060c \u0633\u0627\u0639\u062a \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u0628\u0627 \u0642\u06cc\u0645\u062a \u0631\u0642\u0627\u0628\u062a\u06cc \u062d\u062f\u0648\u062f 5 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062a\u0648\u0645\u0627\u0646 \u0639\u0631\u0636\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u061b \u0627\u0645\u0627 \u0627\u067e\u0644 \u0648\u0627\u0686 6 \u0646\u0647 \u062a\u0646\u0647\u0627 \u0627\u0631\u0632\u0634 \u062e\u0648\u062f \u0631\u0627 \u062d\u0641\u0638 \u06a9\u0631\u062f\u0647\u060c \u0628\u0644\u06a9\u0647 \u0628\u0627 \u0631\u0634\u062f \u0642\u06cc\u0645\u062a \u0627\u0631\u0632 \u06af\u0631\u0627\u0646\u200c\u062a\u0631 \u0646\u06cc\u0632 \u0634\u062f\u0647 \u0648 \u0628\u0627 \u0642\u06cc\u0645\u062a \u062d\u062f\u0627\u0642\u0644\u06cc \u062d\u062f\u0648\u062f 13 \u0627\u0644\u06cc 14 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062a\u0648\u0645\u0627\u0646 \u0628\u0647 \u0641\u0631\u0648\u0634 \u0645\u06cc\u200c\u0631\u0633\u062f. \u0642\u0627\u0628\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u0627\u0631\u0627\u0626\u0647 \u0634\u062f\u0647 \u0631\u0648\u06cc \u0647\u0631 \u062f\u0648 \u0645\u062d\u0635\u0648\u0644 \u0628\u0633\u06cc\u0627\u0631 \u0646\u0632\u062f\u06cc\u06a9 \u0628\u0647 \u0647\u0645 \u0647\u0633\u062a\u0646\u062f \u0648 \u0628\u0647 \u062c\u0632 \u0637\u0631\u0627\u062d\u06cc \u0638\u0627\u0647\u0631\u06cc \u0648 \u0628\u062d\u062b \u0633\u0644\u06cc\u0642\u0647 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646\u060c \u0645\u0633\u0623\u0644\u0647 \u0627\u06a9\u0648\u0633\u06cc\u0633\u062a\u0645 \u0647\u0631 \u0628\u0631\u0646\u062f \u0645\u0637\u0631\u062d \u0627\u0633\u062a. \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0633\u0627\u0645\u0648\u0646\u06af \u0627\u0632 \u0647\u0645\u0647 \u06af\u0648\u0634\u06cc\u200c\u0647\u0627\u06cc \u0633\u0627\u0645\u0633\u0648\u0646\u06af\u060c \u0627\u0646\u062f\u0631\u0648\u06cc\u062f \u0648 iOS \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f\u061b \u0633\u0627\u0639\u062a\u200c \u0647\u0648\u0634\u0645\u0646\u062f \u0627\u067e\u0644 \u0648\u0627\u0686 6 \u062a\u0646\u0647\u0627 \u0628\u0631\u0627\u06cc \u0627\u06a9\u0648\u0633\u06cc\u0633\u062a\u0645 \u0627\u062e\u062a\u0635\u0627\u0635\u06cc \u0627\u06cc\u0646 \u0628\u0631\u0646\u062f \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0648 \u0628\u0627 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0627\u067e\u0644 \u0633\u0627\u0632\u06af\u0627\u0631\u06cc \u062f\u0627\u0631\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u062a\u0648\u0636\u06cc\u062d\u0627\u062a \u0627\u06af\u0631 \u0627\u0632 \u06af\u0648\u0634\u06cc\u200c\u0647\u0627\u06cc \u0633\u0627\u0645\u0633\u0648\u0646\u06af \u06cc\u0627 \u0627\u0646\u062f\u0631\u0648\u06cc\u062f\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f \u0645\u06cc\u200c\u0628\u0627\u06cc\u0633\u062a \u06af\u0644\u06a9\u0633\u06cc \u0648\u0627\u0686 3 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f \u0648 \u0627\u06af\u0631 \u06af\u0648\u0634\u06cc \u0648 \u062a\u0628\u0644\u062a \u0634\u0645\u0627 \u0622\u06cc\u0641\u0648\u0646 \u06cc\u0627 \u0622\u06cc\u067e\u062f \u0627\u0633\u062a \u0627\u0646\u062a\u062e\u0627\u0628 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u200c\u062a\u0631 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u06af\u0644\u0633\u06cc \u0648\u0627\u0686 3 \u0648 \u0627\u0646\u062a\u062e\u0627\u0628 \u06af\u0631\u0627\u0646\u200c\u062a\u0631 \u0648 \u0633\u0627\u0632\u06af\u0627\u0631\u062a\u0631 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0627\u067e\u0644 \u0648\u0627\u0686 6 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/span><\/p>\n<div style='text-align:left' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>\u0627\u067e\u0644 \u0637\u0644\u0627\u06cc\u0647\u200c\u062f\u0627\u0631 \u0628\u0627\u0632\u0627\u0631\u00a0\u0633\u0627\u0639\u062a\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f\u00a0\u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0645\u062f\u062a \u0637\u0648\u0644\u0627\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u0627\u062e\u062a\u0644\u0627\u0641\u060c \u0631\u062a\u0628\u0647 \u0627\u0648\u0644 \u0641\u0631\u0648\u0634 \u062c\u0647\u0627\u0646\u06cc \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0627\u0632 \u06af\u062c\u062a\u200c\u0647\u0627\u06cc \u067e\u0648\u0634\u06cc\u062f\u0646\u06cc \u0631\u0627 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062f\u0627\u0631\u062f. \u0641\u0631\u0648\u0634 \u0628\u0627\u0644\u0627\u06cc \u0627\u067e\u0644 \u0648\u0627\u0686\u200c\u0647\u0627 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u06a9\u06cc\u0641\u06cc\u062a \u0633\u0627\u062e\u062a \u0628\u0627\u0644\u0627 \u0648 \u0645\u0634\u062e\u0635\u0627\u062a \u062c\u0630\u0627\u0628\u060c \u0628\u06cc\u0634 \u0627\u0632 \u0647\u0631 \u0686\u06cc\u0632 \u0645\u062f\u06cc\u0648\u0646 \u0627\u06a9\u0648 \u0633\u06cc\u0633\u062a\u0645 \u06af\u0633\u062a\u0631\u062f\u0647 \u0648 \u0645\u062d\u0628\u0648\u0628 \u0627\u067e\u0644 \u0627\u0633\u062a. \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc\u200c\u0631\u0633\u062f \u062f\u0631 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[122,38,116,15],"tags":[],"class_list":["post-5622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comparison","category-laptop","category-wearable-gadget","category-introduction"],"views":784,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/www.ekalato.com\/blog\/wp-json\/wp\/v2\/posts\/5622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ekalato.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ekalato.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ekalato.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ekalato.com\/blog\/wp-json\/wp\/v2\/comments?post=5622"}],"version-history":[{"count":0,"href":"https:\/\/www.ekalato.com\/blog\/wp-json\/wp\/v2\/posts\/5622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ekalato.com\/blog\/wp-json\/wp\/v2\/media\/5627"}],"wp:attachment":[{"href":"https:\/\/www.ekalato.com\/blog\/wp-json\/wp\/v2\/media?parent=5622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ekalato.com\/blog\/wp-json\/wp\/v2\/categories?post=5622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ekalato.com\/blog\/wp-json\/wp\/v2\/tags?post=5622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}